{"id":4500,"count":1,"description":"","link":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/","name":"True Strength","slug":"true-strength","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>True Strength Archives - WormholeRiders Conventions Corner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"True Strength Archives - WormholeRiders Conventions Corner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/\" \/>\n<meta property=\"og:site_name\" content=\"WormholeRiders Conventions Corner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@WormholeRiders\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/tag\\\/true-strength\\\/\",\"url\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/tag\\\/true-strength\\\/\",\"name\":\"True Strength Archives - WormholeRiders Conventions Corner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/tag\\\/true-strength\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/tag\\\/true-strength\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"True Strength\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#website\",\"url\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/\",\"name\":\"WormholeRiders Conventions Corner\",\"description\":\"Curated Convention Archive. Please go to Wormholeriders.com for our latest interview, convention and series review posts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#organization\",\"name\":\"WormholeRiders Conventions Corner\",\"url\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/WormholeRiders-New-Logo-150TS-Dark.png\",\"contentUrl\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/wp-content\\\/uploads\\\/2012\\\/10\\\/WormholeRiders-New-Logo-150TS-Dark.png\",\"width\":\"150\",\"height\":\"150\",\"caption\":\"WormholeRiders Conventions Corner\"},\"image\":{\"@id\":\"https:\\\/\\\/wormholeriders.org\\\/cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/WormholeRiders\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"True Strength Archives - WormholeRiders Conventions Corner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/","og_locale":"en_US","og_type":"article","og_title":"True Strength Archives - WormholeRiders Conventions Corner","og_url":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/","og_site_name":"WormholeRiders Conventions Corner","twitter_card":"summary_large_image","twitter_site":"@WormholeRiders","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/","url":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/","name":"True Strength Archives - WormholeRiders Conventions Corner","isPartOf":{"@id":"https:\/\/wormholeriders.org\/cc\/#website"},"breadcrumb":{"@id":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wormholeriders.org\/cc\/tag\/true-strength\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wormholeriders.org\/cc\/"},{"@type":"ListItem","position":2,"name":"True Strength"}]},{"@type":"WebSite","@id":"https:\/\/wormholeriders.org\/cc\/#website","url":"https:\/\/wormholeriders.org\/cc\/","name":"WormholeRiders Conventions Corner","description":"Curated Convention Archive. Please go to Wormholeriders.com for our latest interview, convention and series review posts.","publisher":{"@id":"https:\/\/wormholeriders.org\/cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wormholeriders.org\/cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wormholeriders.org\/cc\/#organization","name":"WormholeRiders Conventions Corner","url":"https:\/\/wormholeriders.org\/cc\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wormholeriders.org\/cc\/#\/schema\/logo\/image\/","url":"https:\/\/wormholeriders.org\/cc\/wp-content\/uploads\/2012\/10\/WormholeRiders-New-Logo-150TS-Dark.png","contentUrl":"https:\/\/wormholeriders.org\/cc\/wp-content\/uploads\/2012\/10\/WormholeRiders-New-Logo-150TS-Dark.png","width":"150","height":"150","caption":"WormholeRiders Conventions Corner"},"image":{"@id":"https:\/\/wormholeriders.org\/cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/WormholeRiders"]}]}},"_links":{"self":[{"href":"https:\/\/wormholeriders.org\/cc\/wp-json\/wp\/v2\/tags\/4500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wormholeriders.org\/cc\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wormholeriders.org\/cc\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wormholeriders.org\/cc\/wp-json\/wp\/v2\/posts?tags=4500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}